{"id":6098,"date":"2023-09-02T13:24:00","date_gmt":"2023-09-02T13:24:00","guid":{"rendered":"https:\/\/nemoceans.com\/?p=6098"},"modified":"2024-10-01T16:58:26","modified_gmt":"2024-10-01T16:58:26","slug":"mallorca-daily-bulletin","status":"publish","type":"post","link":"https:\/\/nemoceans.com\/de\/mallorca-daily-bulletin\/","title":{"rendered":"Mallorca Daily Bulletin"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">September, 2023:&nbsp;Die mallorquinische und an ein internationales Publikum gerichtete Wochenzeitung \u201cMallorca Bulletin\u201d publizierte einen exklusiven Artikel \u00fcber Nemocan mit dem \u00fcbersetzten Titel \u201cIn Frieden mit der Natur in der See um Mallorca\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im September erschien ein Interview mit&nbsp;Tobias&nbsp;Hofmann, Mitgr\u00fcnder von Nemocean, durchgef\u00fchrt von Humphrey Carter, dem stellvertretenden Chefredakteur des Mallorca Bulletin. Das Interview umfasst die Hintergr\u00fcnde, das T\u00e4tigkeitsfeld und Besonderheiten von Nemocean Seebestattungen an der K\u00fcste Mallorcas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inhaltlich l\u00e4\u00dft sich das Interview folgenderma\u00dfen zusammenfassen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Die Reise des Lebens ehren: Nemoceans einzigartiger Abschied auf See<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In der heutigen, sich st\u00e4ndig ver\u00e4ndernden globalen Gesellschaft haben sich die M\u00f6glichkeiten f\u00fcr einzigartige und bedeutungsvolle Erfahrungen auf jeden Aspekt des Lebens ausgeweitet, einschlie\u00dflich der Art und Weise, wie wir uns von unseren Lieben verabschieden. Inspiriert von einer altehrw\u00fcrdigen Tradition, die von Generationen von Seeleuten in Deutschland praktiziert wurde, bietet Nemocean, ein Pionierunternehmen mit Sitz im malerischen Mallorca, eine bemerkenswerte M\u00f6glichkeit, das Leben eines Menschen mit einer Trauerfeier auf dem ruhigen Mittelmeer zu feiern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Eine lebenslange Verbindung mit dem Meer<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das von&nbsp;Tobias&nbsp;Hofmann, einem ehemaligen Marineoffizier mit einer tiefen und lebenslangen Verbindung zum Meer, mitbegr\u00fcndete Unternehmen Nemocean steht f\u00fcr einen Wandel in der Bestattungsbranche hin zu individuelleren und alternativen Dienstleistungen. Hofmann, der seit \u00fcber vier Jahren auf Mallorca lebt, erkl\u00e4rt, dass der Bestattungsmarkt einen bedeutenden Wandel durchl\u00e4uft, mit einer wachsenden Nachfrage nach alternativen Bestattungserlebnissen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Abschied mit Anmut<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Abschied von einem geliebten Menschen ist nie leicht, und Nemocean wei\u00df, wie wichtig es ist, den Familien in dieser schwierigen Zeit die n\u00f6tige Unterst\u00fctzung zu bieten. Nemocean hat es sich zur Aufgabe gemacht, eine warme und tr\u00f6stliche Atmosph\u00e4re zu schaffen, wenn die Familien vor der K\u00fcste Mallorcas in See stechen, umgeben von der atemberaubenden Sch\u00f6nheit des Mittelmeers und der Natur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ziel ist es, ein normalerweise d\u00fcsteres und trauerndes Ereignis in eine sanfte und erhebende Abschiedsfeier zu verwandeln, die die Erinnerung an einen geliebten Menschen mit Anmut und W\u00fcrde ehrt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nemoceans einzigartiger Ansatz bietet den Familien Trost und Hilfe bei der Bew\u00e4ltigung der schwierigen Reise des Abschieds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Gesetzeskonformit\u00e4t und Professionalit\u00e4t bei Seebestattungen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Im Jahr 2022 \u00e4nderten sich die spanischen Gesetze, um Seebestattungen unter bestimmten Bedingungen zu erm\u00f6glichen.Nemocean agiert mit Professionalit\u00e4t und arbeitet eng mit der Hafenbeh\u00f6rde zusammen, um sicherzustellen, dass alle erforderlichen Genehmigungen und rechtlichen Anforderungen erf\u00fcllt werden. Das Unternehmen arbeitet auch mit regionalen Kirchengemeinden zusammen und bietet den Familien die M\u00f6glichkeit, geistliche Begleiter in die Zeremonie einzubeziehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ein internationaler Service<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nemocean konzentriert sich auf einen internationalen Markt und hei\u00dft Familien aus der ganzen Welt willkommen, die sich von der Idee eines bewegenden und einzigartigen Abschieds f\u00fcr ihre Lieben angezogen f\u00fchlen. Von s\u00fcdafrikanischen Familien, die seit langem mit Mallorca verbunden sind, bis hin zu Familien aus New York und dar\u00fcber hinaus besteht ein wachsendes Interesse an dieser besonderen Art des Abschiednehmens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Schutz der Umwelt<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nemocean legt gro\u00dfen Wert auf Nachhaltigkeit und Unterst\u00fctzung der Gemeinschaft. Das Unternehmen arbeitet mit lokalen Unternehmen und Mitarbeitern zusammen, um die Gemeinschaft zu unterst\u00fctzen, das Bewusstsein f\u00fcr Umwelt- und maritime Themen zu sch\u00e4rfen und zu relevanten Projekten beizutragen, die den Schutz und die Verbesserung der Umwelt zum Ziel haben.<br><strong><br><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ma\u00dfgeschneiderte Abschiedszeremonien<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nemocean bietet ma\u00dfgeschneiderte Zeremonien, die auf individuelle W\u00fcnsche zugeschnitten sind. Ob mit Segel- oder Motoryachten, Live-Musik, Trauerrednern oder Priestern &#8211; das Team k\u00fcmmert sich um alle Vorbereitungen vor und nach der Veranstaltung und sorgt f\u00fcr einen reibungslosen Ablauf. Die Dienstleistungen werden in Englisch, Deutsch, Spanisch und Franz\u00f6sisch angeboten, um die Familien in dieser emotionalen Zeit zu unterst\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Lang anhaltende Erinnerungen schaffen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Familien erhalten die Koordinaten des Ortes, an dem die Beerdigung stattgefunden hat, so dass sie in der Zukunft f\u00fcr Gedenkfeiern oder kleine Wiederholungsfeiern zur\u00fcckkehren k\u00f6nnen. Nemocean hat es sich zur Aufgabe gemacht, eine respektvolle, behutsame und angenehme Erfahrung zu bieten, die auf die individuellen Bed\u00fcrfnisse jeder Familie zugeschnitten ist und unvergessliche Erinnerungen im Mittelmeer vor der K\u00fcste Mallorcas schafft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Eine einzigartige Feier des Lebens<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In einer sich wandelnden Welt, in der sich die traditionellen Praktiken ver\u00e4ndern, bietet Nemocean eine besondere Art, das Leben eines Menschen zu feiern, indem es Barrieren abbaut und den Familien ein wirklich besonderes und wertvolles Erlebnis bietet. Das Meer, das oft als der ultimative Geburtsort des Lebens auf der Erde und als Symbol f\u00fcr die Ewigkeit angesehen wird, wird zur Kulisse f\u00fcr einen herzlichen Abschied, der f\u00fcr immer in Erinnerung bleiben wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Abschluss<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nemoceans innovativer Ansatz f\u00fcr Bestattungsdienstleistungen spiegelt die sich entwickelnden W\u00fcnsche von Familien wider, die einen bedeutungsvollen und pers\u00f6nlichen Abschied w\u00fcnschen. Das Engagement von Nemocean f\u00fcr Professionalit\u00e4t, Nachhaltigkeit und ma\u00dfgeschneiderte Erlebnisse sorgt daf\u00fcr, dass jeder Abschied zu einer von Herzen kommenden Feier der Lebensreise wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Informationen \u00fcber Nemocean und unsere einzigartigen Bestattungsdienste finden Sie unter (<a href=\"https:\/\/www.nemoceans.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nemoceans.com<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen diesen Blogbeitrag gerne auf Ihrer Website verwenden, um die einzigartigen Bestattungsdienstleistungen von Nemocean zu pr\u00e4sentieren. Wenn Sie bestimmte \u00c4nderungen oder Erg\u00e4nzungen vornehmen m\u00f6chten, lassen Sie es uns bitte wissen, und wir werden Ihnen gerne weiterhelfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>September, 2023:&nbsp;Die mallorquinische und an ein internationales Publikum gerichtete Wochenzeitung \u201cMallorca Bulletin\u201d publizierte einen exklusiven Artikel \u00fcber Nemocan mit dem \u00fcbersetzten Titel \u201cIn Frieden mit der Natur in der See um Mallorca\u201d. Im September erschien ein Interview mit&nbsp;Tobias&nbsp;Hofmann, Mitgr\u00fcnder von Nemocean, durchgef\u00fchrt von Humphrey Carter, dem stellvertretenden Chefredakteur des Mallorca Bulletin. Das Interview umfasst die [&hellip;]<\/p>\n","protected":false},"author":990012,"featured_media":6575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"page_builder":"","footnotes":""},"categories":[174],"tags":[109],"class_list":["post-6098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medien-de","tag-pressemitteilung"],"_links":{"self":[{"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/posts\/6098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/users\/990012"}],"replies":[{"embeddable":true,"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/comments?post=6098"}],"version-history":[{"count":0,"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/posts\/6098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/media\/6575"}],"wp:attachment":[{"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/media?parent=6098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/categories?post=6098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nemoceans.com\/de\/wp-json\/wp\/v2\/tags?post=6098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}